{"id":2015,"date":"2017-04-03T17:09:42","date_gmt":"2017-04-03T17:09:42","guid":{"rendered":"https:\/\/www.grupoxcaret.com\/es\/?p=2015"},"modified":"2017-04-03T17:09:42","modified_gmt":"2017-04-03T17:09:42","slug":"xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association","status":"publish","type":"post","link":"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/","title":{"rendered":"Xenses, Mejor Campa\u00f1a Digital de Viajes: Expertos de la Web Marketing Association"},"content":{"rendered":"<p><span style=\"font-weight: 400;\">Por su extraordinaria campa\u00f1a de lanzamiento del nuevo parque Xenses, Grupo Experiencias Xcaret fue reconocido con el premio a la Mejor Campa\u00f1a de Viajes (Best Travel Online Campaign) por parte de la Web Marketing Association, que reconoce las mejores pr\u00e1cticas internacionales en mercadotecnia digital.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El reconocimiento forma parte de los Internet Advertising Competition Awards, Edici\u00f3n 2017, competencia internacional que se realiza anualmente para todos los sectores de la industria, invitando a las mejores agencias, empresas y destinos por igual, sin importar su tama\u00f1o.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">La campa\u00f1a de lanzamiento de Xenses estuvo dirigida a los mercados de M\u00e9xico y Estados Unidos, generando branding en plataformas como Google, Facebook y Bing. Incluy\u00f3 elementos online y offline, aprovechando medios nuevos como videos 360, videos VR, plataformas de gamification, anuncios rich media interactivos, eMails personalizados y animados, influenciadores invitados, presencia en eventos con cabinas interactivas y desarrollo de un sitio visual y tecnol\u00f3gicamente atractivo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Los Internet Advertising Competition Awards (IAC) fueron desarrollados por la Web Marketing Association para reconocer la excelencia en publicidad en l\u00ednea y reconocer a individuos y organizaciones responsables por crear y publicar publicidad notable en Internet. Para seleccionar a los ganadores, se utilizan criterios como la creatividad, innovaci\u00f3n, impacto, dise\u00f1o, copywriting, uso de los medios y la recordaci\u00f3n de la campa\u00f1a.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Entre otras empresas participantes en la categor\u00eda de travel, est\u00e1n Expedia Media Solutions &amp; Brand USA, Cheapflights, Sabre, y entidades gubernamentales responsables de las marcas-pa\u00eds de destinos como Dinamarca y Suecia. <\/span><\/p>\n<p><span style=\"font-weight: 400;\">El objetivo de la campa\u00f1a fue expresar en medios digitales toda la experiencia sensorial y de entretenimiento que ofrece el parque Xenses, sorprendiendo con aplicaciones altamente interactivas que permitiesen generar una expectativa y deseo de conocer todos los atractivos y actividades del mismo.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">El reconocimiento oficial puede consultarse en la siguiente liga:<\/span><\/p>\n<p><a href=\"http:\/\/www.iacaward.org\/iac\/category\/Travel\/best-travel-ad.html\"><b><i>http:\/\/www.iacaward.org\/iac\/category\/Travel\/best-travel-ad.html<\/i><\/b><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><b>ACERCA DE XENSES<\/b><\/p>\n<p><span style=\"font-weight: 400;\">Xenses es un parque sin igual, un lugar tan divertido como m\u00e1gico, tan asombroso como enigm\u00e1tico y tan disparatado como racional. Aqu\u00ed el visitante es el protagonista de esta experiencia, en un lugar con diferentes escenarios reales e imaginarios que rodear\u00e1n sus sentidos y le llevar\u00e1n a un mundo fant\u00e1stico en donde su percepci\u00f3n ser\u00e1 desafiada.<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Para mayor informaci\u00f3n:<\/span><\/p>\n<p><span style=\"font-weight: 400;\">Iliana Rodr\u00edguez, Subdirecci\u00f3n de Comunicaci\u00f3n y RSC<\/span><\/p>\n<p><span style=\"font-weight: 400;\">irodriguez@experienciasxcaret.com.mx<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por su extraordinaria campa\u00f1a de lanzamiento del nuevo parque Xenses, Grupo Experiencias Xcaret fue reconocido con el premio a la Mejor Campa\u00f1a de Viajes (Best Travel Online Campaign) por parte de la Web Marketing Association, que reconoce las mejores pr\u00e1cticas internacionales en mercadotecnia digital. El reconocimiento forma parte de los Internet Advertising Competition Awards, Edici\u00f3n [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":2020,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[3],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v17.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<meta name=\"description\" content=\"Por su extraordinaria campa\u00f1a de lanzamiento del nuevo parque Xenses, Grupo Experiencias Xcaret fue reconocido con el premio a la Mejor Campa\u00f1a de Viajes.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Xenses, Mejor Campa\u00f1a Digital de Viajes: Expertos de la Web Marketing Association - Grupo Xcaret Sitio Corporativo\" \/>\n<meta property=\"og:description\" content=\"Por su extraordinaria campa\u00f1a de lanzamiento del nuevo parque Xenses, Grupo Experiencias Xcaret fue reconocido con el premio a la Mejor Campa\u00f1a de Viajes.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/\" \/>\n<meta property=\"og:site_name\" content=\"Grupo Xcaret Sitio Corporativo\" \/>\n<meta property=\"article:published_time\" content=\"2017-04-03T17:09:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.grupoxcaret.com\/es\/wp-content\/uploads\/2017\/04\/Premio-Xenses-mini.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"607\" \/>\n\t<meta property=\"og:image:height\" content=\"352\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"dmendozav\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/#organization\",\"name\":\"Grupo Xcaret\",\"url\":\"https:\/\/www.grupoxcaret.com\/es\/\",\"sameAs\":[],\"logo\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/#logo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.grupoxcaret.com\/es\/wp-content\/uploads\/2015\/04\/exx.png\",\"contentUrl\":\"https:\/\/www.grupoxcaret.com\/es\/wp-content\/uploads\/2015\/04\/exx.png\",\"width\":400,\"height\":136,\"caption\":\"Grupo Xcaret\"},\"image\":{\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/#logo\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/#website\",\"url\":\"https:\/\/www.grupoxcaret.com\/es\/\",\"name\":\"Grupo Xcaret Sitio Corporativo\",\"description\":\"Conoce el sitio corporativo de Grupo Xcaret. Encuentra informaci\\u00f3n relevante acerca de nuestra historia, marcas, filosof\\u00eda empresarial, pol\\u00edtica de sostenibilidad y mucho m\\u00e1s.\",\"publisher\":{\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.grupoxcaret.com\/es\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#primaryimage\",\"inLanguage\":\"es\",\"url\":\"https:\/\/www.grupoxcaret.com\/es\/wp-content\/uploads\/2017\/04\/Premio-Xenses-mini.jpg\",\"contentUrl\":\"https:\/\/www.grupoxcaret.com\/es\/wp-content\/uploads\/2017\/04\/Premio-Xenses-mini.jpg\",\"width\":607,\"height\":352},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#webpage\",\"url\":\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/\",\"name\":\"Xenses, Mejor Campa\\u00f1a Digital de Viajes: Expertos de la Web Marketing Association - Grupo Xcaret Sitio Corporativo\",\"isPartOf\":{\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#primaryimage\"},\"datePublished\":\"2017-04-03T17:09:42+00:00\",\"dateModified\":\"2017-04-03T17:09:42+00:00\",\"description\":\"Por su extraordinaria campa\\u00f1a de lanzamiento del nuevo parque Xenses, Grupo Experiencias Xcaret fue reconocido con el premio a la Mejor Campa\\u00f1a de Viajes.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\/\/www.grupoxcaret.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sala de Prensa\",\"item\":\"https:\/\/www.grupoxcaret.com\/es\/seccion\/sala-de-prensa\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Xenses, Mejor Campa\\u00f1a Digital de Viajes: Expertos de la Web Marketing Association\"}]},{\"@type\":\"Article\",\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#webpage\"},\"author\":{\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/#\/schema\/person\/a063bfd3f2c8806ec176d4b2afba737f\"},\"headline\":\"Xenses, Mejor Campa\\u00f1a Digital de Viajes: Expertos de la Web Marketing Association\",\"datePublished\":\"2017-04-03T17:09:42+00:00\",\"dateModified\":\"2017-04-03T17:09:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#webpage\"},\"wordCount\":414,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/#organization\"},\"image\":{\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.grupoxcaret.com\/es\/wp-content\/uploads\/2017\/04\/Premio-Xenses-mini.jpg\",\"articleSection\":[\"Sala de Prensa\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#respond\"]}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/#\/schema\/person\/a063bfd3f2c8806ec176d4b2afba737f\",\"name\":\"dmendozav\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.grupoxcaret.com\/es\/#personlogo\",\"inLanguage\":\"es\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/d0971a818d7242eb0e6a9b000cb0cb6c?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/d0971a818d7242eb0e6a9b000cb0cb6c?s=96&d=mm&r=g\",\"caption\":\"dmendozav\"},\"url\":\"https:\/\/www.grupoxcaret.com\/es\/author\/dmendozav\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"description":"Por su extraordinaria campa\u00f1a de lanzamiento del nuevo parque Xenses, Grupo Experiencias Xcaret fue reconocido con el premio a la Mejor Campa\u00f1a de Viajes.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/","og_locale":"es_ES","og_type":"article","og_title":"Xenses, Mejor Campa\u00f1a Digital de Viajes: Expertos de la Web Marketing Association - Grupo Xcaret Sitio Corporativo","og_description":"Por su extraordinaria campa\u00f1a de lanzamiento del nuevo parque Xenses, Grupo Experiencias Xcaret fue reconocido con el premio a la Mejor Campa\u00f1a de Viajes.","og_url":"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/","og_site_name":"Grupo Xcaret Sitio Corporativo","article_published_time":"2017-04-03T17:09:42+00:00","og_image":[{"width":607,"height":352,"url":"https:\/\/www.grupoxcaret.com\/es\/wp-content\/uploads\/2017\/04\/Premio-Xenses-mini.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"dmendozav","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/www.grupoxcaret.com\/es\/#organization","name":"Grupo Xcaret","url":"https:\/\/www.grupoxcaret.com\/es\/","sameAs":[],"logo":{"@type":"ImageObject","@id":"https:\/\/www.grupoxcaret.com\/es\/#logo","inLanguage":"es","url":"https:\/\/www.grupoxcaret.com\/es\/wp-content\/uploads\/2015\/04\/exx.png","contentUrl":"https:\/\/www.grupoxcaret.com\/es\/wp-content\/uploads\/2015\/04\/exx.png","width":400,"height":136,"caption":"Grupo Xcaret"},"image":{"@id":"https:\/\/www.grupoxcaret.com\/es\/#logo"}},{"@type":"WebSite","@id":"https:\/\/www.grupoxcaret.com\/es\/#website","url":"https:\/\/www.grupoxcaret.com\/es\/","name":"Grupo Xcaret Sitio Corporativo","description":"Conoce el sitio corporativo de Grupo Xcaret. Encuentra informaci\u00f3n relevante acerca de nuestra historia, marcas, filosof\u00eda empresarial, pol\u00edtica de sostenibilidad y mucho m\u00e1s.","publisher":{"@id":"https:\/\/www.grupoxcaret.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.grupoxcaret.com\/es\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"ImageObject","@id":"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#primaryimage","inLanguage":"es","url":"https:\/\/www.grupoxcaret.com\/es\/wp-content\/uploads\/2017\/04\/Premio-Xenses-mini.jpg","contentUrl":"https:\/\/www.grupoxcaret.com\/es\/wp-content\/uploads\/2017\/04\/Premio-Xenses-mini.jpg","width":607,"height":352},{"@type":"WebPage","@id":"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#webpage","url":"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/","name":"Xenses, Mejor Campa\u00f1a Digital de Viajes: Expertos de la Web Marketing Association - Grupo Xcaret Sitio Corporativo","isPartOf":{"@id":"https:\/\/www.grupoxcaret.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#primaryimage"},"datePublished":"2017-04-03T17:09:42+00:00","dateModified":"2017-04-03T17:09:42+00:00","description":"Por su extraordinaria campa\u00f1a de lanzamiento del nuevo parque Xenses, Grupo Experiencias Xcaret fue reconocido con el premio a la Mejor Campa\u00f1a de Viajes.","breadcrumb":{"@id":"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inicio","item":"https:\/\/www.grupoxcaret.com\/es\/"},{"@type":"ListItem","position":2,"name":"Sala de Prensa","item":"https:\/\/www.grupoxcaret.com\/es\/seccion\/sala-de-prensa\/"},{"@type":"ListItem","position":3,"name":"Xenses, Mejor Campa\u00f1a Digital de Viajes: Expertos de la Web Marketing Association"}]},{"@type":"Article","@id":"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#article","isPartOf":{"@id":"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#webpage"},"author":{"@id":"https:\/\/www.grupoxcaret.com\/es\/#\/schema\/person\/a063bfd3f2c8806ec176d4b2afba737f"},"headline":"Xenses, Mejor Campa\u00f1a Digital de Viajes: Expertos de la Web Marketing Association","datePublished":"2017-04-03T17:09:42+00:00","dateModified":"2017-04-03T17:09:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#webpage"},"wordCount":414,"commentCount":0,"publisher":{"@id":"https:\/\/www.grupoxcaret.com\/es\/#organization"},"image":{"@id":"https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#primaryimage"},"thumbnailUrl":"https:\/\/www.grupoxcaret.com\/es\/wp-content\/uploads\/2017\/04\/Premio-Xenses-mini.jpg","articleSection":["Sala de Prensa"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.grupoxcaret.com\/es\/xenses-mejor-campana-digital-viajes-expertos-la-web-marketing-association\/#respond"]}]},{"@type":"Person","@id":"https:\/\/www.grupoxcaret.com\/es\/#\/schema\/person\/a063bfd3f2c8806ec176d4b2afba737f","name":"dmendozav","image":{"@type":"ImageObject","@id":"https:\/\/www.grupoxcaret.com\/es\/#personlogo","inLanguage":"es","url":"https:\/\/secure.gravatar.com\/avatar\/d0971a818d7242eb0e6a9b000cb0cb6c?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/d0971a818d7242eb0e6a9b000cb0cb6c?s=96&d=mm&r=g","caption":"dmendozav"},"url":"https:\/\/www.grupoxcaret.com\/es\/author\/dmendozav\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/www.grupoxcaret.com\/es\/wp-json\/wp\/v2\/posts\/2015"}],"collection":[{"href":"https:\/\/www.grupoxcaret.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.grupoxcaret.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.grupoxcaret.com\/es\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"https:\/\/www.grupoxcaret.com\/es\/wp-json\/wp\/v2\/comments?post=2015"}],"version-history":[{"count":0,"href":"https:\/\/www.grupoxcaret.com\/es\/wp-json\/wp\/v2\/posts\/2015\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.grupoxcaret.com\/es\/wp-json\/wp\/v2\/media\/2020"}],"wp:attachment":[{"href":"https:\/\/www.grupoxcaret.com\/es\/wp-json\/wp\/v2\/media?parent=2015"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.grupoxcaret.com\/es\/wp-json\/wp\/v2\/categories?post=2015"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.grupoxcaret.com\/es\/wp-json\/wp\/v2\/tags?post=2015"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}